{"id":2601,"count":1,"description":"","link":"https:\/\/slickpix.de\/en\/tag\/intermediate-reifen\/","name":"Intermediate tires","slug":"intermediate-reifen","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Intermediate Reifen Archive - SLICKPIX Magazin<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/slickpix.de\/en\/tag\/intermediate-reifen\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Intermediate Reifen Archive - SLICKPIX Magazin\" \/>\n<meta property=\"og:url\" content=\"https:\/\/slickpix.de\/en\/tag\/intermediate-reifen\/\" \/>\n<meta property=\"og:site_name\" content=\"SLICKPIX Magazin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/slickpix.de\\\/tag\\\/intermediate-reifen\\\/\",\"url\":\"https:\\\/\\\/slickpix.de\\\/tag\\\/intermediate-reifen\\\/\",\"name\":\"Intermediate Reifen Archive - SLICKPIX Magazin\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/slickpix.de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/slickpix.de\\\/tag\\\/intermediate-reifen\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/slickpix.de\\\/tag\\\/intermediate-reifen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/slickpix.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Intermediate Reifen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/slickpix.de\\\/#website\",\"url\":\"https:\\\/\\\/slickpix.de\\\/\",\"name\":\"SLICKPIX Magazin\",\"description\":\"Motorsport Pictures &amp; Stories\",\"publisher\":{\"@id\":\"https:\\\/\\\/slickpix.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/slickpix.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/slickpix.de\\\/#organization\",\"name\":\"Slickpix\",\"url\":\"https:\\\/\\\/slickpix.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/slickpix.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/slickpix.de\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/slickpix-logo.png\",\"contentUrl\":\"https:\\\/\\\/slickpix.de\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/slickpix-logo.png\",\"width\":800,\"height\":180,\"caption\":\"Slickpix\"},\"image\":{\"@id\":\"https:\\\/\\\/slickpix.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/slickpix\",\"https:\\\/\\\/instagram.com\\\/slickpix.de\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Intermediate Reifen Archive - SLICKPIX Magazin","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/slickpix.de\/en\/tag\/intermediate-reifen\/","og_locale":"en_US","og_type":"article","og_title":"Intermediate Reifen Archive - SLICKPIX Magazin","og_url":"https:\/\/slickpix.de\/en\/tag\/intermediate-reifen\/","og_site_name":"SLICKPIX Magazin","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/slickpix.de\/tag\/intermediate-reifen\/","url":"https:\/\/slickpix.de\/tag\/intermediate-reifen\/","name":"Intermediate Reifen Archive - SLICKPIX Magazin","isPartOf":{"@id":"https:\/\/slickpix.de\/#website"},"breadcrumb":{"@id":"https:\/\/slickpix.de\/tag\/intermediate-reifen\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/slickpix.de\/tag\/intermediate-reifen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/slickpix.de\/"},{"@type":"ListItem","position":2,"name":"Intermediate Reifen"}]},{"@type":"WebSite","@id":"https:\/\/slickpix.de\/#website","url":"https:\/\/slickpix.de\/","name":"SLICKPIX Magazine","description":"Motorsport Pictures &amp; Stories","publisher":{"@id":"https:\/\/slickpix.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/slickpix.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/slickpix.de\/#organization","name":"Slickpix","url":"https:\/\/slickpix.de\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/slickpix.de\/#\/schema\/logo\/image\/","url":"https:\/\/slickpix.de\/wp-content\/uploads\/2025\/12\/slickpix-logo.png","contentUrl":"https:\/\/slickpix.de\/wp-content\/uploads\/2025\/12\/slickpix-logo.png","width":800,"height":180,"caption":"Slickpix"},"image":{"@id":"https:\/\/slickpix.de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/slickpix","https:\/\/instagram.com\/slickpix.de\/"]}]}},"_links":{"self":[{"href":"https:\/\/slickpix.de\/en\/wp-json\/wp\/v2\/tags\/2601","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/slickpix.de\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/slickpix.de\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/slickpix.de\/en\/wp-json\/wp\/v2\/posts?tags=2601"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}