{"id":14721,"date":"2023-10-10T15:17:00","date_gmt":"2023-10-10T13:17:00","guid":{"rendered":"https:\/\/slickpix.de\/?post_type=slickpix_gallery&#038;p=14721"},"modified":"2026-03-17T15:19:14","modified_gmt":"2026-03-17T14:19:14","slug":"dtm-red-bull-ring-2023","status":"publish","type":"slickpix_gallery","link":"https:\/\/slickpix.de\/en\/gallery\/dtm-red-bull-ring-2023\/","title":{"rendered":"DTM Red Bull Ring 2023"},"content":{"rendered":"","protected":false},"featured_media":14734,"template":"","slickpix_gallery_category":[1925],"slickpix_gallery_tag":[1919,1936],"class_list":["post-14721","slickpix_gallery","type-slickpix_gallery","status-publish","has-post-thumbnail","hentry","slickpix_gallery_category-austria","slickpix_gallery_tag-dtm","slickpix_gallery_tag-red-bull-ring"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DTM Red Bull Ring 2023 - SLICKPIX Magazin<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/slickpix.de\/en\/gallery\/dtm-red-bull-ring-2023\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DTM Red Bull Ring 2023 - SLICKPIX Magazin\" \/>\n<meta property=\"og:url\" content=\"https:\/\/slickpix.de\/en\/gallery\/dtm-red-bull-ring-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"SLICKPIX Magazin\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/slickpix\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-17T14:19:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/slickpix.de\/wp-content\/uploads\/spx-gallery\/dtm-red-bull-ring-2023\/DTM_OeR23_13.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/slickpix.de\\\/gallery\\\/dtm-red-bull-ring-2023\\\/\",\"url\":\"https:\\\/\\\/slickpix.de\\\/gallery\\\/dtm-red-bull-ring-2023\\\/\",\"name\":\"DTM Red Bull Ring 2023 - SLICKPIX Magazin\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/slickpix.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/slickpix.de\\\/gallery\\\/dtm-red-bull-ring-2023\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/slickpix.de\\\/gallery\\\/dtm-red-bull-ring-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/slickpix.de\\\/wp-content\\\/uploads\\\/spx-gallery\\\/dtm-red-bull-ring-2023\\\/DTM_OeR23_13.jpg\",\"datePublished\":\"2023-10-10T13:17:00+00:00\",\"dateModified\":\"2026-03-17T14:19:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/slickpix.de\\\/gallery\\\/dtm-red-bull-ring-2023\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/slickpix.de\\\/gallery\\\/dtm-red-bull-ring-2023\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/slickpix.de\\\/gallery\\\/dtm-red-bull-ring-2023\\\/#primaryimage\",\"url\":\"https:\\\/\\\/slickpix.de\\\/wp-content\\\/uploads\\\/spx-gallery\\\/dtm-red-bull-ring-2023\\\/DTM_OeR23_13.jpg\",\"contentUrl\":\"https:\\\/\\\/slickpix.de\\\/wp-content\\\/uploads\\\/spx-gallery\\\/dtm-red-bull-ring-2023\\\/DTM_OeR23_13.jpg\",\"width\":800,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/slickpix.de\\\/gallery\\\/dtm-red-bull-ring-2023\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/slickpix.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Galerien\",\"item\":\"https:\\\/\\\/slickpix.de\\\/gallery\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"DTM Red Bull Ring 2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/slickpix.de\\\/#website\",\"url\":\"https:\\\/\\\/slickpix.de\\\/\",\"name\":\"SLICKPIX Magazin\",\"description\":\"Motorsport Pictures &amp; Stories\",\"publisher\":{\"@id\":\"https:\\\/\\\/slickpix.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/slickpix.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/slickpix.de\\\/#organization\",\"name\":\"Slickpix\",\"url\":\"https:\\\/\\\/slickpix.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/slickpix.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/slickpix.de\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/slickpix-logo.png\",\"contentUrl\":\"https:\\\/\\\/slickpix.de\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/slickpix-logo.png\",\"width\":800,\"height\":180,\"caption\":\"Slickpix\"},\"image\":{\"@id\":\"https:\\\/\\\/slickpix.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/slickpix\",\"https:\\\/\\\/instagram.com\\\/slickpix.de\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DTM Red Bull Ring 2023 - SLICKPIX Magazin","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/slickpix.de\/en\/gallery\/dtm-red-bull-ring-2023\/","og_locale":"en_US","og_type":"article","og_title":"DTM Red Bull Ring 2023 - SLICKPIX Magazin","og_url":"https:\/\/slickpix.de\/en\/gallery\/dtm-red-bull-ring-2023\/","og_site_name":"SLICKPIX Magazin","article_publisher":"https:\/\/facebook.com\/slickpix","article_modified_time":"2026-03-17T14:19:14+00:00","og_image":[{"width":800,"height":1200,"url":"https:\/\/slickpix.de\/wp-content\/uploads\/spx-gallery\/dtm-red-bull-ring-2023\/DTM_OeR23_13.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/slickpix.de\/gallery\/dtm-red-bull-ring-2023\/","url":"https:\/\/slickpix.de\/gallery\/dtm-red-bull-ring-2023\/","name":"DTM Red Bull Ring 2023 - SLICKPIX Magazin","isPartOf":{"@id":"https:\/\/slickpix.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/slickpix.de\/gallery\/dtm-red-bull-ring-2023\/#primaryimage"},"image":{"@id":"https:\/\/slickpix.de\/gallery\/dtm-red-bull-ring-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/slickpix.de\/wp-content\/uploads\/spx-gallery\/dtm-red-bull-ring-2023\/DTM_OeR23_13.jpg","datePublished":"2023-10-10T13:17:00+00:00","dateModified":"2026-03-17T14:19:14+00:00","breadcrumb":{"@id":"https:\/\/slickpix.de\/gallery\/dtm-red-bull-ring-2023\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/slickpix.de\/gallery\/dtm-red-bull-ring-2023\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/slickpix.de\/gallery\/dtm-red-bull-ring-2023\/#primaryimage","url":"https:\/\/slickpix.de\/wp-content\/uploads\/spx-gallery\/dtm-red-bull-ring-2023\/DTM_OeR23_13.jpg","contentUrl":"https:\/\/slickpix.de\/wp-content\/uploads\/spx-gallery\/dtm-red-bull-ring-2023\/DTM_OeR23_13.jpg","width":800,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/slickpix.de\/gallery\/dtm-red-bull-ring-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/slickpix.de\/"},{"@type":"ListItem","position":2,"name":"Galerien","item":"https:\/\/slickpix.de\/gallery\/"},{"@type":"ListItem","position":3,"name":"DTM Red Bull Ring 2023"}]},{"@type":"WebSite","@id":"https:\/\/slickpix.de\/#website","url":"https:\/\/slickpix.de\/","name":"SLICKPIX Magazine","description":"Motorsport Pictures &amp; Stories","publisher":{"@id":"https:\/\/slickpix.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/slickpix.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/slickpix.de\/#organization","name":"Slickpix","url":"https:\/\/slickpix.de\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/slickpix.de\/#\/schema\/logo\/image\/","url":"https:\/\/slickpix.de\/wp-content\/uploads\/2025\/12\/slickpix-logo.png","contentUrl":"https:\/\/slickpix.de\/wp-content\/uploads\/2025\/12\/slickpix-logo.png","width":800,"height":180,"caption":"Slickpix"},"image":{"@id":"https:\/\/slickpix.de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/slickpix","https:\/\/instagram.com\/slickpix.de\/"]}]}},"_links":{"self":[{"href":"https:\/\/slickpix.de\/en\/wp-json\/wp\/v2\/slickpix_gallery\/14721","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/slickpix.de\/en\/wp-json\/wp\/v2\/slickpix_gallery"}],"about":[{"href":"https:\/\/slickpix.de\/en\/wp-json\/wp\/v2\/types\/slickpix_gallery"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/slickpix.de\/en\/wp-json\/wp\/v2\/media\/14734"}],"wp:attachment":[{"href":"https:\/\/slickpix.de\/en\/wp-json\/wp\/v2\/media?parent=14721"}],"wp:term":[{"taxonomy":"slickpix_gallery_category","embeddable":true,"href":"https:\/\/slickpix.de\/en\/wp-json\/wp\/v2\/slickpix_gallery_category?post=14721"},{"taxonomy":"slickpix_gallery_tag","embeddable":true,"href":"https:\/\/slickpix.de\/en\/wp-json\/wp\/v2\/slickpix_gallery_tag?post=14721"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}