{"id":13652,"date":"2025-05-16T14:03:00","date_gmt":"2025-05-16T12:03:00","guid":{"rendered":"https:\/\/slickpix.de\/?post_type=slickpix_gallery&#038;p=13652"},"modified":"2026-03-17T14:06:34","modified_gmt":"2026-03-17T13:06:34","slug":"wec-6h-spa-2025","status":"publish","type":"slickpix_gallery","link":"https:\/\/slickpix.de\/en\/gallery\/wec-6h-spa-2025\/","title":{"rendered":"WEC 6 Hours of Spa 2025"},"content":{"rendered":"","protected":false},"featured_media":13693,"template":"","slickpix_gallery_category":[1902],"slickpix_gallery_tag":[1921,1903,1899],"class_list":["post-13652","slickpix_gallery","type-slickpix_gallery","status-publish","has-post-thumbnail","hentry","slickpix_gallery_category-belgium","slickpix_gallery_tag-6h-spa","slickpix_gallery_tag-spa","slickpix_gallery_tag-wec"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>WEC 6h Spa 2025 - SLICKPIX Magazin<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/slickpix.de\/en\/gallery\/wec-6h-spa-2025\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"WEC 6h Spa 2025 - SLICKPIX Magazin\" \/>\n<meta property=\"og:url\" content=\"https:\/\/slickpix.de\/en\/gallery\/wec-6h-spa-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"SLICKPIX Magazin\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/slickpix\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-17T13:06:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/slickpix.de\/wp-content\/uploads\/spx-gallery\/wec-6h-spa-2025\/WEC_SPA25_40.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/slickpix.de\\\/gallery\\\/wec-6h-spa-2025\\\/\",\"url\":\"https:\\\/\\\/slickpix.de\\\/gallery\\\/wec-6h-spa-2025\\\/\",\"name\":\"WEC 6h Spa 2025 - SLICKPIX Magazin\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/slickpix.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/slickpix.de\\\/gallery\\\/wec-6h-spa-2025\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/slickpix.de\\\/gallery\\\/wec-6h-spa-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/slickpix.de\\\/wp-content\\\/uploads\\\/spx-gallery\\\/wec-6h-spa-2025\\\/WEC_SPA25_40.jpg\",\"datePublished\":\"2025-05-16T12:03:00+00:00\",\"dateModified\":\"2026-03-17T13:06:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/slickpix.de\\\/gallery\\\/wec-6h-spa-2025\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/slickpix.de\\\/gallery\\\/wec-6h-spa-2025\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/slickpix.de\\\/gallery\\\/wec-6h-spa-2025\\\/#primaryimage\",\"url\":\"https:\\\/\\\/slickpix.de\\\/wp-content\\\/uploads\\\/spx-gallery\\\/wec-6h-spa-2025\\\/WEC_SPA25_40.jpg\",\"contentUrl\":\"https:\\\/\\\/slickpix.de\\\/wp-content\\\/uploads\\\/spx-gallery\\\/wec-6h-spa-2025\\\/WEC_SPA25_40.jpg\",\"width\":1800,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/slickpix.de\\\/gallery\\\/wec-6h-spa-2025\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/slickpix.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Galerien\",\"item\":\"https:\\\/\\\/slickpix.de\\\/gallery\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"WEC 6h Spa 2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/slickpix.de\\\/#website\",\"url\":\"https:\\\/\\\/slickpix.de\\\/\",\"name\":\"SLICKPIX Magazin\",\"description\":\"Motorsport Pictures &amp; Stories\",\"publisher\":{\"@id\":\"https:\\\/\\\/slickpix.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/slickpix.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/slickpix.de\\\/#organization\",\"name\":\"Slickpix\",\"url\":\"https:\\\/\\\/slickpix.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/slickpix.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/slickpix.de\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/slickpix-logo.png\",\"contentUrl\":\"https:\\\/\\\/slickpix.de\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/slickpix-logo.png\",\"width\":800,\"height\":180,\"caption\":\"Slickpix\"},\"image\":{\"@id\":\"https:\\\/\\\/slickpix.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/slickpix\",\"https:\\\/\\\/instagram.com\\\/slickpix.de\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"WEC 6h Spa 2025 - SLICKPIX Magazin","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/slickpix.de\/en\/gallery\/wec-6h-spa-2025\/","og_locale":"en_US","og_type":"article","og_title":"WEC 6h Spa 2025 - SLICKPIX Magazin","og_url":"https:\/\/slickpix.de\/en\/gallery\/wec-6h-spa-2025\/","og_site_name":"SLICKPIX Magazin","article_publisher":"https:\/\/facebook.com\/slickpix","article_modified_time":"2026-03-17T13:06:34+00:00","og_image":[{"width":1800,"height":1200,"url":"https:\/\/slickpix.de\/wp-content\/uploads\/spx-gallery\/wec-6h-spa-2025\/WEC_SPA25_40.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/slickpix.de\/gallery\/wec-6h-spa-2025\/","url":"https:\/\/slickpix.de\/gallery\/wec-6h-spa-2025\/","name":"WEC 6h Spa 2025 - SLICKPIX Magazin","isPartOf":{"@id":"https:\/\/slickpix.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/slickpix.de\/gallery\/wec-6h-spa-2025\/#primaryimage"},"image":{"@id":"https:\/\/slickpix.de\/gallery\/wec-6h-spa-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/slickpix.de\/wp-content\/uploads\/spx-gallery\/wec-6h-spa-2025\/WEC_SPA25_40.jpg","datePublished":"2025-05-16T12:03:00+00:00","dateModified":"2026-03-17T13:06:34+00:00","breadcrumb":{"@id":"https:\/\/slickpix.de\/gallery\/wec-6h-spa-2025\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/slickpix.de\/gallery\/wec-6h-spa-2025\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/slickpix.de\/gallery\/wec-6h-spa-2025\/#primaryimage","url":"https:\/\/slickpix.de\/wp-content\/uploads\/spx-gallery\/wec-6h-spa-2025\/WEC_SPA25_40.jpg","contentUrl":"https:\/\/slickpix.de\/wp-content\/uploads\/spx-gallery\/wec-6h-spa-2025\/WEC_SPA25_40.jpg","width":1800,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/slickpix.de\/gallery\/wec-6h-spa-2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/slickpix.de\/"},{"@type":"ListItem","position":2,"name":"Galerien","item":"https:\/\/slickpix.de\/gallery\/"},{"@type":"ListItem","position":3,"name":"WEC 6h Spa 2025"}]},{"@type":"WebSite","@id":"https:\/\/slickpix.de\/#website","url":"https:\/\/slickpix.de\/","name":"SLICKPIX Magazine","description":"Motorsport Pictures &amp; Stories","publisher":{"@id":"https:\/\/slickpix.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/slickpix.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/slickpix.de\/#organization","name":"Slickpix","url":"https:\/\/slickpix.de\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/slickpix.de\/#\/schema\/logo\/image\/","url":"https:\/\/slickpix.de\/wp-content\/uploads\/2025\/12\/slickpix-logo.png","contentUrl":"https:\/\/slickpix.de\/wp-content\/uploads\/2025\/12\/slickpix-logo.png","width":800,"height":180,"caption":"Slickpix"},"image":{"@id":"https:\/\/slickpix.de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/slickpix","https:\/\/instagram.com\/slickpix.de\/"]}]}},"_links":{"self":[{"href":"https:\/\/slickpix.de\/en\/wp-json\/wp\/v2\/slickpix_gallery\/13652","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/slickpix.de\/en\/wp-json\/wp\/v2\/slickpix_gallery"}],"about":[{"href":"https:\/\/slickpix.de\/en\/wp-json\/wp\/v2\/types\/slickpix_gallery"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/slickpix.de\/en\/wp-json\/wp\/v2\/media\/13693"}],"wp:attachment":[{"href":"https:\/\/slickpix.de\/en\/wp-json\/wp\/v2\/media?parent=13652"}],"wp:term":[{"taxonomy":"slickpix_gallery_category","embeddable":true,"href":"https:\/\/slickpix.de\/en\/wp-json\/wp\/v2\/slickpix_gallery_category?post=13652"},{"taxonomy":"slickpix_gallery_tag","embeddable":true,"href":"https:\/\/slickpix.de\/en\/wp-json\/wp\/v2\/slickpix_gallery_tag?post=13652"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}